{"id":2767,"date":"2025-02-17T21:41:18","date_gmt":"2025-02-17T21:41:18","guid":{"rendered":"https:\/\/jlvholding.com\/co\/?p=2767"},"modified":"2025-02-17T21:47:12","modified_gmt":"2025-02-17T21:47:12","slug":"el-crecimiento-de-una-lider-katherine-perez","status":"publish","type":"post","link":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/","title":{"rendered":"El Crecimiento de una L\u00edder, Katherine P\u00e9rez"},"content":{"rendered":"<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-2768 alignleft\" src=\"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-225x300.jpeg 225w, https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-768x1024.jpeg 768w, https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-1152x1536.jpeg 1152w, https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-640x853.jpeg 640w, https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-150x200.jpeg 150w, https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM.jpeg 1200w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/strong><\/p>\n<p data-start=\"187\" data-end=\"520\">En <strong data-start=\"190\" data-end=\"205\">JLV Holding<\/strong> seguimos consolid\u00e1ndonos como un grupo empresarial s\u00f3lido en Medell\u00edn y Colombia, apostando por la <strong data-start=\"305\" data-end=\"349\">innovaci\u00f3n, el desarrollo y la expansi\u00f3n<\/strong> en diversas industrias clave. Gracias al esfuerzo, la visi\u00f3n estrat\u00e9gica y la dedicaci\u00f3n de nuestro equipo, hemos logrado posicionarnos como un referente en el mercado.<\/p>\n<p data-start=\"522\" data-end=\"782\">Uno de los mayores ejemplos de liderazgo dentro del grupo es el de <strong data-start=\"589\" data-end=\"608\">Katherine P\u00e9rez<\/strong>, quien con su esfuerzo, servicio y compromiso ha sido pieza clave en el crecimiento de JLV Holding, demostrando que la excelencia y la determinaci\u00f3n son la base del \u00e9xito.<\/p>\n<h2 data-start=\"1738\" data-end=\"1801\"><strong data-start=\"1741\" data-end=\"1799\">Katherine P\u00e9rez: Un Ejemplo de Liderazgo y Crecimiento<\/strong><\/h2>\n<p data-start=\"1803\" data-end=\"1988\">En el mundo empresarial, el liderazgo es clave para el \u00e9xito, y <strong data-start=\"1867\" data-end=\"1886\">Katherine P\u00e9rez<\/strong> es un claro ejemplo de c\u00f3mo la pasi\u00f3n y la dedicaci\u00f3n pueden llevar a una empresa a nuevos niveles.<\/p>\n<p data-start=\"1990\" data-end=\"2367\">Desde sus inicios en JLV Holding, Katherine ha demostrado un compromiso excepcional, impulsando estrategias innovadoras y fortaleciendo cada una de las marcas del grupo. Su visi\u00f3n estrat\u00e9gica ha permitido la <strong data-start=\"2198\" data-end=\"2232\">expansi\u00f3n de nuestras empresas<\/strong>, el desarrollo de nuevas l\u00edneas de negocio y la consolidaci\u00f3n de JLV Holding como un referente en el sector empresarial en Colombia.<\/p>\n<h2 data-start=\"2369\" data-end=\"2410\"><strong data-start=\"2372\" data-end=\"2408\">Nuestro Compromiso con el Futuro<\/strong><\/h2>\n<p data-start=\"2412\" data-end=\"2571\">En <strong data-start=\"2415\" data-end=\"2430\">JLV Holding<\/strong>, seguimos trabajando para fortalecer nuestras marcas y ampliar nuestra presencia en el mercado. Nuestros objetivos para este a\u00f1o incluyen:<\/p>\n<p data-start=\"2573\" data-end=\"2833\">\u2705 <strong data-start=\"2575\" data-end=\"2613\">Expansi\u00f3n en el Oriente Antioque\u00f1o<\/strong> con nuevas oportunidades de negocio.<br data-start=\"2650\" data-end=\"2653\" \/>\u2705 <strong data-start=\"2655\" data-end=\"2680\">Alianzas estrat\u00e9gicas<\/strong> para potenciar el crecimiento de nuestras empresas.<br data-start=\"2732\" data-end=\"2735\" \/>\u2705 <strong data-start=\"2737\" data-end=\"2776\">Innovaci\u00f3n en productos y servicios<\/strong> para seguir satisfaciendo las necesidades del mercado.<\/p>\n<p data-start=\"2835\" data-end=\"2984\">\ud83d\udce9 <strong data-start=\"2838\" data-end=\"2982\">\u00a1S\u00e9 parte de nuestro crecimiento! Cont\u00e1ctanos y descubre c\u00f3mo JLV Holding est\u00e1 transformando el panorama empresarial en Medell\u00edn y Colombia.<\/strong><\/p>\n<p><strong>\ud83d\udce9<\/strong><strong> \u00bfQuieres ser parte de esta historia de \u00e9xito? <\/strong><strong><a href=\"https:\/\/jlvholding.com\/co\/contactenos\/\">Cont\u00e1ctanos<\/a> y crezcamos juntos.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En JLV Holding seguimos consolid\u00e1ndonos como un grupo empresarial s\u00f3lido en Medell\u00edn y Colombia, apostando por la innovaci\u00f3n, el desarrollo y la expansi\u00f3n en diversas industrias clave. Gracias al esfuerzo, la visi\u00f3n estrat\u00e9gica y la dedicaci\u00f3n de nuestro equipo, hemos logrado posicionarnos como un referente en el mercado. Uno de los mayores ejemplos de liderazgo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"categories":[14,71],"tags":[],"class_list":["post-2767","post","type-post","status-publish","format-standard","hentry","category-holding","category-recursos-humanos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Crecimiento de una L\u00edder, Katherine P\u00e9rez - JLV Holding<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Crecimiento de una L\u00edder, Katherine P\u00e9rez - JLV Holding\" \/>\n<meta property=\"og:description\" content=\"En JLV Holding seguimos consolid\u00e1ndonos como un grupo empresarial s\u00f3lido en Medell\u00edn y Colombia, apostando por la innovaci\u00f3n, el desarrollo y la expansi\u00f3n en diversas industrias clave. Gracias al esfuerzo, la visi\u00f3n estrat\u00e9gica y la dedicaci\u00f3n de nuestro equipo, hemos logrado posicionarnos como un referente en el mercado. Uno de los mayores ejemplos de liderazgo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/\" \/>\n<meta property=\"og:site_name\" content=\"JLV Holding\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-17T21:41:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-17T21:47:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-225x300.jpeg\" \/>\n<meta name=\"author\" content=\"Maria Clara Quiroz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Clara Quiroz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/\",\"url\":\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/\",\"name\":\"El Crecimiento de una L\u00edder, Katherine P\u00e9rez - JLV Holding\",\"isPartOf\":{\"@id\":\"https:\/\/jlvholding.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-225x300.jpeg\",\"datePublished\":\"2025-02-17T21:41:18+00:00\",\"dateModified\":\"2025-02-17T21:47:12+00:00\",\"author\":{\"@id\":\"https:\/\/jlvholding.com\/#\/schema\/person\/b8748fa0d9545922aaa6282c4e8408f2\"},\"breadcrumb\":{\"@id\":\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#primaryimage\",\"url\":\"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM.jpeg\",\"contentUrl\":\"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM.jpeg\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/jlvholding.com\/co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Crecimiento de una L\u00edder, Katherine P\u00e9rez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jlvholding.com\/#website\",\"url\":\"https:\/\/jlvholding.com\/\",\"name\":\"JLV Holding\",\"description\":\"EXPERIENCE IN MOTION\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jlvholding.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/jlvholding.com\/#\/schema\/person\/b8748fa0d9545922aaa6282c4e8408f2\",\"name\":\"Maria Clara Quiroz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/jlvholding.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/jlvholding.com\/co\/wp-content\/litespeed\/avatar\/e48d8d6a445bf9ed927233411fb3eb99.jpg?ver=1778247564\",\"contentUrl\":\"https:\/\/jlvholding.com\/co\/wp-content\/litespeed\/avatar\/e48d8d6a445bf9ed927233411fb3eb99.jpg?ver=1778247564\",\"caption\":\"Maria Clara Quiroz\"},\"url\":\"https:\/\/jlvholding.com\/co\/author\/mquiroz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Crecimiento de una L\u00edder, Katherine P\u00e9rez - JLV Holding","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/","og_locale":"es_ES","og_type":"article","og_title":"El Crecimiento de una L\u00edder, Katherine P\u00e9rez - JLV Holding","og_description":"En JLV Holding seguimos consolid\u00e1ndonos como un grupo empresarial s\u00f3lido en Medell\u00edn y Colombia, apostando por la innovaci\u00f3n, el desarrollo y la expansi\u00f3n en diversas industrias clave. Gracias al esfuerzo, la visi\u00f3n estrat\u00e9gica y la dedicaci\u00f3n de nuestro equipo, hemos logrado posicionarnos como un referente en el mercado. Uno de los mayores ejemplos de liderazgo [&hellip;]","og_url":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/","og_site_name":"JLV Holding","article_published_time":"2025-02-17T21:41:18+00:00","article_modified_time":"2025-02-17T21:47:12+00:00","og_image":[{"url":"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-225x300.jpeg"}],"author":"Maria Clara Quiroz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maria Clara Quiroz","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/","url":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/","name":"El Crecimiento de una L\u00edder, Katherine P\u00e9rez - JLV Holding","isPartOf":{"@id":"https:\/\/jlvholding.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#primaryimage"},"image":{"@id":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#primaryimage"},"thumbnailUrl":"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM-225x300.jpeg","datePublished":"2025-02-17T21:41:18+00:00","dateModified":"2025-02-17T21:47:12+00:00","author":{"@id":"https:\/\/jlvholding.com\/#\/schema\/person\/b8748fa0d9545922aaa6282c4e8408f2"},"breadcrumb":{"@id":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#primaryimage","url":"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM.jpeg","contentUrl":"https:\/\/jlvholding.com\/co\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-17-at-4.27.40-PM.jpeg","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/jlvholding.com\/co\/2025\/02\/17\/el-crecimiento-de-una-lider-katherine-perez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/jlvholding.com\/co\/"},{"@type":"ListItem","position":2,"name":"El Crecimiento de una L\u00edder, Katherine P\u00e9rez"}]},{"@type":"WebSite","@id":"https:\/\/jlvholding.com\/#website","url":"https:\/\/jlvholding.com\/","name":"JLV Holding","description":"EXPERIENCE IN MOTION","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jlvholding.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Person","@id":"https:\/\/jlvholding.com\/#\/schema\/person\/b8748fa0d9545922aaa6282c4e8408f2","name":"Maria Clara Quiroz","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/jlvholding.com\/#\/schema\/person\/image\/","url":"https:\/\/jlvholding.com\/co\/wp-content\/litespeed\/avatar\/e48d8d6a445bf9ed927233411fb3eb99.jpg?ver=1778247564","contentUrl":"https:\/\/jlvholding.com\/co\/wp-content\/litespeed\/avatar\/e48d8d6a445bf9ed927233411fb3eb99.jpg?ver=1778247564","caption":"Maria Clara Quiroz"},"url":"https:\/\/jlvholding.com\/co\/author\/mquiroz\/"}]}},"_links":{"self":[{"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/posts\/2767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/comments?post=2767"}],"version-history":[{"count":6,"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/posts\/2767\/revisions"}],"predecessor-version":[{"id":2774,"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/posts\/2767\/revisions\/2774"}],"wp:attachment":[{"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/media?parent=2767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/categories?post=2767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jlvholding.com\/co\/wp-json\/wp\/v2\/tags?post=2767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}